{"id":2578,"date":"2020-01-16T17:44:25","date_gmt":"2020-01-16T17:44:25","guid":{"rendered":"https:\/\/www.sosmedecincasa.com\/?p=2578"},"modified":"2020-05-01T10:28:32","modified_gmt":"2020-05-01T10:28:32","slug":"6-raisons-qui-vous-empechent-darreter-de-fumer","status":"publish","type":"post","link":"https:\/\/www.sosmedecincasa.com\/ar\/2020\/01\/16\/6-raisons-qui-vous-empechent-darreter-de-fumer\/","title":{"rendered":"6 raisons qui vous emp\u00eachent d&rsquo;arr\u00eater de fumer"},"content":{"rendered":"<p>Stress, peur de grossir, rituels, craving\u2026 Quels sont les principaux freins \u00e0 l\u2019arr\u00eat du tabac ?<\/p>\n\n\n\n<p>1 \u2013 Les sympt\u00f4mes du manque physique<br>Un des premiers freins \u00e0 l\u2019arr\u00eat du tabac est en lien direct avec la d\u00e9pendance physique.Abandonner la cigarette entra\u00eene en effet un manque physique qui se traduit par des maux de t\u00eate, une d\u00e9prime, une irritabilit\u00e9, une labilit\u00e9 \u00e9motionnelle ou encore des troubles du sommeil. Autant de sympt\u00f4mes&nbsp;que redoutent les candidats \u00e0 l\u2019arr\u00eat du tabac<\/p>\n\n\n\n<p>2 \u2013 La peur de grossir<br>Il s\u2019agit d\u2019un frein constamment \u00e9voqu\u00e9 par les personnes qui cherchent \u00e0 arr\u00eater de fumer.<\/p>\n\n\n\n<p>3 \u2013 Habitudes et rituels<br>Un autre frein \u00e0 l\u2019arr\u00eat du tabac d\u00e9coule de la d\u00e9pendance comportementale et concerne les habitudes, les rituels et m\u00eame les associations de la cigarette, notamment avec le caf\u00e9 ou l\u2019alcool.<\/p>\n\n\n\n<p>4 \u2013 Entourage fumeur, d\u00e9fi \u00e0 plusieurs !<br>Arr\u00eater de fumer est encore plus difficile lorsque votre entourage fume aussi.<\/p>\n\n\n\n<p>5 \u2013 Une pulsion irr\u00e9pressible : le craving<br>La d\u00e9pendance psychologique constitue une entrave majeure dans le sevrage tabagique. \u201cPenser \u00e0 une cigarette, voir un fumeur, passer du temps avec des amis fumeurs, apercevoir un bureau de tabac<\/p>\n\n\n\n<p>6 \u2013 Trop stress\u00e9 pour arr\u00eater de fumer ?<br>Les personnes qui tentent sans succ\u00e8s d\u2019arr\u00eater de fumer \u00e9voquent \u00e9galement la barri\u00e8re du stress. Mais attention, consid\u00e9rer que le tabac est un facteur d\u00e9stressant est en r\u00e9alit\u00e9 une id\u00e9e-re\u00e7ue. \u201cFumer entra\u00eene un pic puis une baisse de nicotine qui g\u00e9n\u00e8re alors un manque et une source de stress.<\/p>","protected":false},"excerpt":{"rendered":"<p>Stress, peur de grossir, rituels, craving\u2026 Quels sont les principaux freins \u00e0 l\u2019arr\u00eat du tabac ? 1 \u2013 Les sympt\u00f4mes du manque physiqueUn des premiers freins \u00e0 l\u2019arr\u00eat du tabac est en lien direct avec la d\u00e9pendance physique.Abandonner la cigarette entra\u00eene en effet un manque physique qui se traduit par des maux de t\u00eate, une [&hellip;]<\/p>","protected":false},"author":8,"featured_media":2579,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[718,717,716,715],"tags":[1064,1066,1067,1065,1063],"yst_prominent_words":[779,755,777,775,785,759,751,765,783,767,753,773,761,781,757,789,771,769,787,763],"class_list":["post-2578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medecin-a-domicile","category-medecin-de-garde","category-medecin-de-nuit","category-sos-medecin-casa","tag-medecin-a-domicile-casablanca","tag-medecin-de-garde-casablanca","tag-medecin-de-nuit-casablanca","tag-sos-docteurs-casablanca","tag-sos-medecins-casablanca"],"_links":{"self":[{"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/posts\/2578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/comments?post=2578"}],"version-history":[{"count":0,"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/posts\/2578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/media\/2579"}],"wp:attachment":[{"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/media?parent=2578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/categories?post=2578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/tags?post=2578"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/ar\/wp-json\/wp\/v2\/yst_prominent_words?post=2578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}