{"id":2563,"date":"2020-01-13T07:58:13","date_gmt":"2020-01-13T07:58:13","guid":{"rendered":"https:\/\/www.sosmedecincasa.com\/?p=2563"},"modified":"2020-05-01T10:30:30","modified_gmt":"2020-05-01T10:30:30","slug":"lanatomie-des-yeux","status":"publish","type":"post","link":"https:\/\/www.sosmedecincasa.com\/de\/2020\/01\/13\/lanatomie-des-yeux\/","title":{"rendered":"L&rsquo;anatomie des yeux"},"content":{"rendered":"<p>L&rsquo;anatomie des yeux est complexe et explique la multitude de maladies oculaires. Les troubles de la vue sont vari\u00e9s et toucheraient 20% de la population. Voici donc quelques conseils pour prendre soin de vos yeux.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Privil\u00e9giez une lumi\u00e8re claire mais pas \u00e9blouissante<\/li><li>Baillez ! Un exercice tr\u00e8s simple et efficace pour humidifier et nettoyer les yeux.<\/li><li>Restez dans la p\u00e9nombre : la lumi\u00e8re tamis\u00e9e repose les yeux, le corps et l\u2019esprit.<\/li><li>Clignez des yeux.<\/li><li>De l\u2019air frais ! A\u00e9rez r\u00e9guli\u00e8rement ou bien allez en promenade.<\/li><li>Prot\u00e9gez-vous de la lumi\u00e8re du soleil.<\/li><li>Regarder progressivement au loin pour faire travailler les muscles int\u00e9rieurs comme ext\u00e9rieurs et faire travailler la flexibilit\u00e9 de la r\u00e9tine.<\/li><li>Bien manger: Aliments contenant de la vitamine A, C, E et rester bien hydrat\u00e9.<br><\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>L&rsquo;anatomie des yeux est complexe et explique la multitude de maladies oculaires. Les troubles de la vue sont vari\u00e9s et toucheraient 20% de la population. Voici donc quelques conseils pour prendre soin de vos yeux. Privil\u00e9giez une lumi\u00e8re claire mais pas \u00e9blouissante Baillez ! Un exercice tr\u00e8s simple et efficace pour humidifier et nettoyer les [&hellip;]<\/p>","protected":false},"author":8,"featured_media":2552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[718,717,716,715],"tags":[1064,1066,1067,1065,1063],"yst_prominent_words":[888,890,891,889],"class_list":["post-2563","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medecin-a-domicile","category-medecin-de-garde","category-medecin-de-nuit","category-sos-medecin-casa","tag-medecin-a-domicile-casablanca","tag-medecin-de-garde-casablanca","tag-medecin-de-nuit-casablanca","tag-sos-docteurs-casablanca","tag-sos-medecins-casablanca"],"_links":{"self":[{"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/posts\/2563","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/comments?post=2563"}],"version-history":[{"count":0,"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/posts\/2563\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/media\/2552"}],"wp:attachment":[{"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/media?parent=2563"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/categories?post=2563"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/tags?post=2563"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/de\/wp-json\/wp\/v2\/yst_prominent_words?post=2563"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}