{"id":2922,"date":"2020-09-26T13:57:30","date_gmt":"2020-09-26T13:57:30","guid":{"rendered":"https:\/\/www.sosmedecincasa.com\/?p=2922"},"modified":"2024-05-03T14:09:33","modified_gmt":"2024-05-03T14:09:33","slug":"sos-medecin-a-domicile-dar-bouazza","status":"publish","type":"post","link":"https:\/\/www.sosmedecincasa.com\/es\/2020\/09\/26\/sos-medecin-a-domicile-dar-bouazza\/","title":{"rendered":"SOS M\u00c9DECIN \u00c0 DOMICILE DAR BOUAZZA"},"content":{"rendered":"<h2 class=\"wp-block-heading\">CONSULTATION VISITE M\u00c9DECIN \u00c0 DOMICILE DAR BOUAZZA<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/sosmedecinsmaroc.ma\/wp-content\/uploads\/2020\/05\/medecin-1-300x129.jpg\" alt=\"medecin sos\" class=\"wp-image-3226\"\/><\/figure>\n\n\n\n<p>Vous habitez \u00e0 Dar Bouazza et vous avez besoin d\u2019un m\u00e9decin g\u00e9n\u00e9raliste urgentiste ou sp\u00e9cialiste pour tout type d\u2019urgence, un m\u00e9decin arrive chez vous dans les plus brefs d\u00e9lais sos m\u00e9decins est l\u00e0 pour r\u00e9pondre \u00e0 vos besoins d\u2019urgence le m\u00e9decin le plus proche de votre zone se d\u00e9place rapidement&nbsp; chez vous \u00e0 Dar Bouazza et environs.<\/p>\n\n\n\n<p>Bien souvent, les urgences arrivent aux moments o\u00f9 l\u2019on s\u2019y attend le moins, et il arrive que vous ayez besoin d\u2019un m\u00e9decin \u00e0 domicile , L\u2019intervention se fait en 10 minutes environ.<\/p>\n\n\n\n<p>SOS M\u00e9decins Dar Bouazza est l\u00e0 pour r\u00e9pondre \u00e0 tout genre de situation d\u2019urgence. Avec notre \u00e9quipe de m\u00e9decins g\u00e9n\u00e9ralistes et sp\u00e9cialistes d\u00e9vou\u00e9e pour leurs patients,<\/p>\n\n\n\n<p>SOS M\u00e9decins Dar Bouazza vous propose une intervention imm\u00e9diate d\u2019un m\u00e9decin \u00e0 domicile Casablanca pour toutes vos urgences de sant\u00e9 !<\/p>\n\n\n\n<p>Quel que soit votre besoin m\u00e9dical ou celui de vos proches, SOS M\u00c9DECINS CASABLANCA vous donne la possibilit\u00e9 de joindre en un clic un m\u00e9decin \u00e0 domicile Casablanca 24 heures sur 24.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SOS M\u00c9DECINS DAR BOUAZZA<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/sosmedecinsmaroc.ma\/wp-content\/uploads\/2020\/05\/IMG-4254-1-1-300x225.jpg\" alt=\"voiture sos medecins maroc\" class=\"wp-image-3224\"\/><\/figure>\n\n\n\n<p>SOS MEDECINS DAR BOUAZZA met \u00e0 votre disposition une \u00e9quipe de m\u00e9decins de garde \u00e0 Casablanca joignable 24h\/24.<\/p>\n\n\n\n<p>Le m\u00e9decin le plus proche&nbsp; chez vous&nbsp;interviendra en moins de 10 Minutes sur Casablanca et ses environs.<\/p>\n\n\n\n<p>SOS MEDECINS&nbsp;DAR BOUAZZA&nbsp;vous donne acc\u00e8s \u00e0 une \u00e9quipe de m\u00e9decins qualifi\u00e9s. En quelques minutes seulement vous pouvez obtenir un m\u00e9decin \u00e0 domicile Casablanca.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">SOS M\u00c9DECINS DE NUIT&nbsp;DAR BOUAZZA<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/sosmedecinsmaroc.ma\/wp-content\/uploads\/2020\/09\/LOGO-SOS-MEDECIN-300x101.png\" alt=\"\" class=\"wp-image-3243\"\/><\/figure>\n\n\n\n<p>SOS MEDECINS DAR BOUAZZA DE NUIT est \u00e0 votre disposition une \u00e9quipe de m\u00e9decins de garde \u00e0 Casablanca joignables 24 heures sur 24.<\/p>\n\n\n\n<p>Appelez le centre de r\u00e9gulation m\u00e9dicale au 05 22 20 20 20 ou 05 22 47 47 47 pour avoir un m\u00e9decin de nuit urgentiste en moin de 15 min.&nbsp;<\/p>\n\n\n\n<p>Votre Sant\u00e9, notre priorit\u00e9.<\/p>\n\n\n\n<p>Nous ferons toujours plus pour votre sant\u00e9.<\/p>","protected":false},"excerpt":{"rendered":"<p>CONSULTATION VISITE M\u00c9DECIN \u00c0 DOMICILE DAR BOUAZZA Vous habitez \u00e0 Dar Bouazza et vous avez besoin d\u2019un m\u00e9decin g\u00e9n\u00e9raliste urgentiste ou sp\u00e9cialiste pour tout type d\u2019urgence, un m\u00e9decin arrive chez vous dans les plus brefs d\u00e9lais sos m\u00e9decins est l\u00e0 pour r\u00e9pondre \u00e0 vos besoins d\u2019urgence le m\u00e9decin le plus proche de votre zone se [&hellip;]<\/p>","protected":false},"author":8,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,718,717,716,715],"tags":[1073,1070,1064,1066,1067,1069,1065,1686,1063,1068,1071],"yst_prominent_words":[1188,1189,1178,1187,1181,1179,606,1176,1212,1211,1191,1180,482,1210,1197],"class_list":["post-2922","post","type-post","status-publish","format-standard","hentry","category-autres","category-medecin-a-domicile","category-medecin-de-garde","category-medecin-de-nuit","category-sos-medecin-casa","tag-allo-tabib-casablanca","tag-docteur-a-domicile-casablanca","tag-medecin-a-domicile-casablanca","tag-medecin-de-garde-casablanca","tag-medecin-de-nuit-casablanca","tag-sos-casablanca","tag-sos-docteurs-casablanca","tag-sos-medecin-a-domicile-dar-bouazza","tag-sos-medecins-casablanca","tag-sos-urgences-casablanca","tag-urgence-casablanca"],"_links":{"self":[{"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/posts\/2922","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/comments?post=2922"}],"version-history":[{"count":1,"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/posts\/2922\/revisions"}],"predecessor-version":[{"id":2923,"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/posts\/2922\/revisions\/2923"}],"wp:attachment":[{"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/media?parent=2922"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/categories?post=2922"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/tags?post=2922"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/es\/wp-json\/wp\/v2\/yst_prominent_words?post=2922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}