{"id":3084,"date":"2021-10-18T10:39:17","date_gmt":"2021-10-18T10:39:17","guid":{"rendered":"https:\/\/www.sosmedecincasa.com\/?p=3084"},"modified":"2024-05-03T13:38:36","modified_gmt":"2024-05-03T13:38:36","slug":"crises-dangoisse-a-repetition-5-conseils-pour-les-attenuer","status":"publish","type":"post","link":"https:\/\/www.sosmedecincasa.com\/zh\/2021\/10\/18\/crises-dangoisse-a-repetition-5-conseils-pour-les-attenuer\/","title":{"rendered":"CRISES D\u2019ANGOISSE \u00c0 R\u00c9P\u00c9TITION : 5 CONSEILS POUR LES ATT\u00c9NUER"},"content":{"rendered":"<p>Les crises d\u2019angoisse, ou crises de panique, seraient monnaie courante pour environ 1 \u00e0 3 % de la population fran\u00e7aise. Dans deux cas sur trois, ce sont les femmes qui sont les plus concern\u00e9es. Qu\u2019est-ce qu\u2019une crise d\u2019angoisse exactement ? Quelles peuvent en \u00eatre les causes et comment les apaiser naturellement ? D\u00e9couvrez tous nos miraculeux conseils !<\/p>\n\n\n\n<p style=\"text-align:center\"><strong><em>Qu\u2019est-ce qu\u2019une crise d\u2019angoisse ?<\/em><\/strong><\/p>\n\n\n\n<p>Une&nbsp;<strong>crise d\u2019angoisse<\/strong>&nbsp;se ressent par une sensation de mal-\u00eatre, une appr\u00e9hension intense, une crainte, une peur, une impression de catastrophe imminente, le c\u0153ur qui s\u2019emballe, accompagn\u00e9 d\u2019une difficult\u00e9 \u00e0 respirer.<\/p>\n\n\n\n<p>Si ces \u00e9motions \u00e9voluent vers un \u00e9tat pathologique, qu\u2019elles deviennent intenses et soudaines tout en engendrant des sympt\u00f4mes physiques sp\u00e9cifiques, on peut parler de crise d\u2019angoisse aigu\u00eb, ou&nbsp;<strong>crise de panique.<\/strong><\/p>\n\n\n\n<p style=\"text-align:center\"><strong><em>Quelles sont les causes possibles des crises d\u2019angoisse ?<\/em><\/strong><\/p>\n\n\n\n<p>La plupart du temps, une crise d\u2019angoisse peut survenir sur un fond d\u2019anxi\u00e9t\u00e9 ou de d\u00e9pression plus ou moins persistant. Cela se rencontre chez des personnes&nbsp;<strong>particuli\u00e8rement vuln\u00e9rables au stress<\/strong>&nbsp;et aux circonstances environnantes.<\/p>\n\n\n\n<p>Une crise d\u2019angoisse aigu\u00eb peut \u00eatre totalement spontan\u00e9e, mais peut aussi arriver \u00e0 la suite d\u2019un facteur d\u00e9clenchant :<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>un stress brutal ;<\/li><li>une perturbation \u00e9motionnelle ou une p\u00e9riode de fatigue ;<\/li><li>lors d\u2019une confrontation avec une phobie ;<\/li><li>apr\u00e8s avoir pris certains m\u00e9dicaments, produit toxique ou stimulant ;<\/li><li>durant le sevrage de substances comme l\u2019alcool, les opiac\u00e9s, la caf\u00e9ine, etc.<\/li><\/ul>\n\n\n\n<p style=\"text-align:center\"><strong><em>Crises d\u2019angoisse \u00e0 r\u00e9p\u00e9tition : comment les traiter aturellement ?<\/em><\/strong><\/p>\n\n\n\n<p>Si les crises d\u2019angoisse fortes et r\u00e9p\u00e9t\u00e9es doivent faire l\u2019objet d\u2019une consultation m\u00e9dicale, quelques astuces naturelles peuvent aider \u00e0 les traiter rapidement, et \u00e0 retrouver du bien-\u00eatre sur le moyen et long terme :<\/p>\n\n\n\n<p style=\"text-align:center\"><strong><em>La phytoth\u00e9rapie pour traiter les angoisses<\/em><\/strong><\/p>\n\n\n\n<p>Par chance, la nature nous offre de\u00a0<a href=\"https:\/\/www.sosmedecincasa.com\/zh\/\">nombreuses plantes aux vertus relaxantes<\/a>, calmantes et apaisantes ! Pour retrouver un peu de s\u00e9r\u00e9nit\u00e9, la\u00a0<strong>lavande<\/strong>\u00a0est sans conteste LA plante qu\u2019il vous faut. Son parfum proven\u00e7al ultra relaxant utilis\u00e9 sous forme d\u2019huile essentielle par exemple permet de\u00a0<a href=\"https:\/\/www.sosmedecincasa.com\/zh\/\">calmer le stress<\/a>\u00a0et l\u2019anxi\u00e9t\u00e9, de favoriser le retour au calme et un sommeil plus apais\u00e9.<\/p>\n\n\n\n<p>D\u2019autres plantes comme l\u2019<a href=\"https:\/\/www.sosmedecincasa.com\/zh\/\">aub\u00e9pine<\/a>, la\u00a0<a href=\"https:\/\/www.sosmedecincasa.com\/zh\/\">rhodiola<\/a>, la passiflore ou encore le traditionnel tilleul peuvent aider \u00e0 retrouver naturellement une sensation de calme. Vous pouvez les utiliser en infusion (pour le tilleul par exemple) coupl\u00e9e \u00e0 une cure de compl\u00e9ments alimentaires pendant les p\u00e9riodes o\u00f9 vous vous sentez plus stress\u00e9s ou plus anxieux.<\/p>\n\n\n\n<p style=\"text-align:center\"><strong><em>L\u2019activit\u00e9 physique pour limiter les crises d\u2019angoisse<\/em><\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.lesmiraculeux.com\/blogs\/conseils-sante\/comment-se-motiver-a-faire-du-sport\">Pratiquer une activit\u00e9 sportive<\/a>&nbsp;donne l\u2019opportunit\u00e9 d\u2019assurer aussi bien un bon \u00e9tat psychologique et \u00e9motionnel en plus de contribuer au maintien de la forme physique.&nbsp; En r\u00e9alisant votre entra\u00eenement, votre cerveau va s\u00e9cr\u00e9ter de la s\u00e9rotonine (la mol\u00e9cule du \u201cbien-\u00eatre !), ce qui va contribuer \u00e0 votre d\u00e9tente, tout en favorisant un sommeil de meilleure qualit\u00e9.<\/p>\n\n\n\n<p>Le sport peut aussi \u00eatre un moyen sain d\u2019ext\u00e9rioriser ses \u00e9motions, notamment lorsque les crises d\u2019angoisse ou de panique sont d\u00e9clench\u00e9es \u00e0 la suite d\u2019un \u00e9v\u00e9nement qui a g\u00e9n\u00e9r\u00e9 des \u00e9motions n\u00e9gatives comme la col\u00e8re ou la frustration.<\/p>\n\n\n\n<p style=\"text-align:center\"><strong><em>La pratique de \u00ab sports doux \u00bb pour favoriser la relaxation<\/em><\/strong><\/p>\n\n\n\n<p>Si vous n\u2019\u00eates pas tr\u00e8s branch\u00e9(e) sport, vous pouvez aussi vous tourner vers des activit\u00e9s plus douces, inspir\u00e9es de l\u2019Asie o\u00f9 la connexion corps-esprit est beaucoup plus valoris\u00e9e qu\u2019en Occident. Le\u00a0<strong>tai-chi<\/strong>\u00a0par exemple est reconnu pour am\u00e9liorer la sant\u00e9 mentale et la ma\u00eetrise de la respiration, tout en favorisant la prise de conscience de son corps. Le\u00a0<strong>Qi Gong<\/strong>\u00a0fera quant \u00e0 lui travailler votre concentration, tout en am\u00e9liorant votre \u00e9nergie vitale. Le\u00a0<a href=\"https:\/\/www.sosmedecincasa.com\/zh\/\">yoga<\/a>\u00a0est \u00e9galement recommand\u00e9 pour lutter contre les crises d\u2019angoisse.<\/p>\n\n\n\n<p style=\"text-align:center\"><strong><em>La coh\u00e9rence cardiaque et la m\u00e9ditation pour apaiser les tensions<\/em><\/strong><\/p>\n\n\n\n<p>Pour vous aider \u00e0 mieux g\u00e9rer vos \u00e9motions au quotidien, la coh\u00e9rence cardiaque coupl\u00e9e \u00e0 la\u00a0<a href=\"https:\/\/www.sosmedecincasa.com\/zh\/\">m\u00e9ditation<\/a>\u00a0repr\u00e9sente une solution naturelle facile \u00e0 mettre en place.<\/p>\n\n\n\n<p>Plus que la dur\u00e9e des s\u00e9ances, c\u2019est la r\u00e9gularit\u00e9 qui vous apportera les bienfaits de ces deux pratiques. De nombreuses applications sont disponibles, gratuites et payantes sous forme de programmes adapt\u00e9s \u00e0 vos besoins.<\/p>\n\n\n\n<p>Vous pouvez \u00e9galement retrouver des s\u00e9ances guid\u00e9es en vid\u00e9o sur Youtube, \u00e0 r\u00e9aliser le matin au r\u00e9veil, le soir avant le coucher ou \u00e0 tout moment de la journ\u00e9e lorsque vous en ressentez le besoin !<\/p>","protected":false},"excerpt":{"rendered":"<p>Les crises d\u2019angoisse, ou crises de panique, seraient monnaie courante pour environ 1 \u00e0 3 % de la population fran\u00e7aise. Dans deux cas sur trois, ce sont les femmes qui sont les plus concern\u00e9es. Qu\u2019est-ce qu\u2019une crise d\u2019angoisse exactement ? Quelles peuvent en \u00eatre les causes et comment les apaiser naturellement ? D\u00e9couvrez tous nos [&hellip;]<\/p>","protected":false},"author":8,"featured_media":3092,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,718,717,716,715],"tags":[1073,1070,1064,1066,1067,1069,1065,1063,1068,1071],"yst_prominent_words":[1522,1521,168,1510,1516,1512,1515,1511,1517,1519,1523,1518,1508,1506,1505,1509,1507,1406,769,378],"class_list":["post-3084","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-autres","category-medecin-a-domicile","category-medecin-de-garde","category-medecin-de-nuit","category-sos-medecin-casa","tag-allo-tabib-casablanca","tag-docteur-a-domicile-casablanca","tag-medecin-a-domicile-casablanca","tag-medecin-de-garde-casablanca","tag-medecin-de-nuit-casablanca","tag-sos-casablanca","tag-sos-docteurs-casablanca","tag-sos-medecins-casablanca","tag-sos-urgences-casablanca","tag-urgence-casablanca"],"_links":{"self":[{"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/posts\/3084","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/comments?post=3084"}],"version-history":[{"count":1,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/posts\/3084\/revisions"}],"predecessor-version":[{"id":3093,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/posts\/3084\/revisions\/3093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/media\/3092"}],"wp:attachment":[{"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/media?parent=3084"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/categories?post=3084"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/tags?post=3084"},{"taxonomy":"yst_prominent_words","embeddable":true,"href":"https:\/\/www.sosmedecincasa.com\/zh\/wp-json\/wp\/v2\/yst_prominent_words?post=3084"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}